{"id":11840,"date":"2021-10-22T06:12:39","date_gmt":"2021-10-22T05:12:39","guid":{"rendered":"https:\/\/interiorlover.in\/?p=11840"},"modified":"2021-10-22T06:20:52","modified_gmt":"2021-10-22T05:20:52","slug":"the-zeal-home-sonali-patel-design-mumbai","status":"publish","type":"post","link":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/","title":{"rendered":"The Zeal Home | Sonali Patel Design | Mumbai"},"content":{"rendered":"\n<p>\u00a0<strong>\u2018The Zeal Home\u2019, <\/strong>an elegant & warm Mumbai Home, by <strong><a href=\"http:\/\/www.instagram.com\/Sonalipateldesign\/\">Sonali Patel Design<\/a><\/strong><\/p>\n\n\n\n<p>The three-bedroom space spread over 1,000 sq.ft. is home to a middle-aged couple, their old mother and a young daughter. Each one had a different vision for their personal sections of the home. In beautiful adherence to the client\u2019s brief, we created a home that brings together the varied opinions of every family member into an amalgamated whole where the beauty and unicity of the individual tastes as well as that of the collective is respectfully maintained. Each area of the home has a unique vibe to it, yet they blend together harmoniously with the perfect juxtaposition of warm and cold tones. The idea was not to redistribute spaces or create different zones, but to create a more fluid solution that creates personal spaces without losing the family touch. This overall approach was able to transform the space into a simple but elegant and warm home.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"773\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11842\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11842\"  class=\"wp-image-11842 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1-1160x773.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1-1160x773.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1-800x533.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg 1773w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"773\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11843\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai2.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11843\"  class=\"wp-image-11843 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai2-1160x773.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai2-1160x773.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai2-800x533.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai2.jpg 1773w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"773\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11844\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai3.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11844\"  class=\"wp-image-11844 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai3-1160x773.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai3-1160x773.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai3-800x533.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai3.jpg 1773w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"773\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11845\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai4.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11845\"  class=\"wp-image-11845 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai4-1160x773.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai4-1160x773.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai4-800x533.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai4.jpg 1773w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"1740\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11841\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai0.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11841\"  class=\"wp-image-11841 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai0-1160x1740.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai0-1160x1740.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai0-800x1200.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai0.jpg 1182w\" ><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>Living, Dining & Kitchen<\/strong><\/p>\n\n\n\n<p>It came up in a conversation that the clients have always been drawn towards blue colour, it is then we thought of using blue as an accent threading through the home. A blue sapphire sofa along with an irish cream single-seater, form the central seating layout for the living room. With walls that are painted soft beige, a shell is created which is a dull monotone. This allowed us to experiment with the furniture and other elements by using colour and texture. The dual textured television unit is a beautiful example of this thought process, which indeed enhances the beauty and style of the living space. The dining area has an intimate yet luxurious setting with a mango wood table for four in a cosy nook, complete with statement upholstered chairs. The kitchen brings aesthetics and functionality together in a breath-taking symphony of white and blue surfaces.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"1788\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11847\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai6.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11847\"  class=\"wp-image-11847 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai6-1160x1788.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai6-1160x1788.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai6-800x1233.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai6.jpg 1166w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"1754\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11848\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai7.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11848\"  class=\"wp-image-11848 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai7-1160x1754.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai7-1160x1754.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai7-800x1210.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai7.jpg 1177w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"1576\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11846\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai5.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11846\"  class=\"wp-image-11846 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai5-1160x1576.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai5-1160x1576.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai5-800x1087.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai5.jpg 1242w\" ><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>Master bedroom<\/strong><\/p>\n\n\n\n<p>This bedroom for a middle-aged couple was designed to perfect the vibe of the occupants. Bedroom being small in size, the challenge was to make it spacious and airy. We decided to highlight the bed wall mainly, keeping everything else very subtle. Leaning against a beautiful spring green wall is a blue sapphire headboard that seamlessly blends in to complete a master bedroom space. Cool hues amalgamated for a sense of calm and respite from hectic city lives.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"773\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11849\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai8.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11849\"  class=\"wp-image-11849 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai8-1160x773.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai8-1160x773.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai8-800x533.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai8.jpg 1773w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"773\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11850\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai9.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11850\"  class=\"wp-image-11850 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai9-1160x773.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai9-1160x773.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai9-800x533.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai9.jpg 1773w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"1740\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11851\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai10.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11851\"  class=\"wp-image-11851 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai10-1160x1740.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai10-1160x1740.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai10-800x1200.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai10.jpg 1182w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"773\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11852\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai11.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11852\"  class=\"wp-image-11852 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai11-1160x773.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai11-1160x773.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai11-800x533.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai11.jpg 1773w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"1740\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11853\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai12.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11853\"  class=\"wp-image-11853 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai12-1160x1740.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai12-1160x1740.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai12-800x1200.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai12.jpg 1182w\" ><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>Daughter\u2019s bedroom<\/strong><\/p>\n\n\n\n<p>In this bedroom we incorporated a floral wallpaper with French panelling to give a sense of feminine and chic character to the room. The wallpaper and soft furnishings all come together giving the space a style and language of its own.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"773\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11854\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai13.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11854\"  class=\"wp-image-11854 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai13-1160x773.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai13-1160x773.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai13-800x533.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai13.jpg 1773w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"773\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11855\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai14.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11855\"  class=\"wp-image-11855 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai14-1160x773.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai14-1160x773.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai14-800x533.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai14.jpg 1773w\" ><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>Parent\u2019s bedroom<\/strong><\/p>\n\n\n\n<p>While all the other elements are condensed to the bare minimum, the cedar brown headboard and the Victorian wall lights add drama to the subtle wallpaper finished wall, revealing the true essence of the space.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"773\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11857\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai16.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11857\"  class=\"wp-image-11857 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai16-1160x773.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai16-1160x773.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai16-800x533.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai16.jpg 1773w\" ><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img  loading=\"lazy\"  decoding=\"async\"  width=\"1160\"  height=\"1740\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"11856\"  data-full-url=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai15.jpg\"  data-link=\"https:\/\/interiorlover.in\/?attachment_id=11856\"  class=\"wp-image-11856 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1160px) 100vw, 1160px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai15-1160x1740.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai15-1160x1740.jpg 1160w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai15-800x1200.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai15.jpg 1182w\" ><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>\u201cTrue to its name, the home is the alluring zeal of the family with a sheen of elegance and beauty.\u201d<\/strong><\/p>\n\n\n\n<p><strong>FACT FILE :<\/strong><\/p>\n\n\n\n<p><strong>Project Name : The Zeal Home<\/strong><br><strong>Design Firm : <a href=\"http:\/\/www.instagram.com\/Sonalipateldesign\/\">Sonali Patel Design<\/a> <\/strong><br><strong>Principal Designer : Sonali Patel <\/strong><br><strong>Project Location : Chembur, Mumbai<\/strong><br><strong>Project Type : Residential Interiors<\/strong><br><strong>Carpet Area : 1,000 Sq.Ft.<\/strong><br><strong>Project Completion : August, 2021<\/strong><br><strong>Photography Credit: <a href=\"http:\/\/www.instagram.com\/Bizou.Photos\/\">Biju Gopal<\/a> <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u2018The Zeal Home\u2019, an elegant &#038; warm Mumbai Home, by Sonali Patel Design The three-bedroom space spread over 1,000 sq.ft. is home to a middle-aged couple, their old mother and&hellip;<\/p>\n","protected":false},"author":2,"featured_media":11842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,35,21],"tags":[53,27,96,17,45,46,88,52,47,108,405,370,56,402,317,30,439],"powerkit_post_featured":[],"class_list":{"0":"post-11840","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-interior","8":"category-projects","9":"category-residential","10":"tag-apartmentinterior","11":"tag-architecture","12":"tag-bizouphotos","13":"tag-interior","14":"tag-interiordesign","15":"tag-interiordesigninspiration","16":"tag-interiorfurniture","17":"tag-interiorlover-in","18":"tag-interiorphotography","19":"tag-interiorstyling","20":"tag-luxury-architecture","21":"tag-luxury-interior","22":"tag-luxuryhome","23":"tag-modern-home","24":"tag-modern-interior","25":"tag-residentialinterior","26":"tag-sonali-patel-design"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Zeal Home | Sonali Patel Design | Mumbai &#8211; Interiorlover Projects<\/title>\n<meta name=\"description\" content=\"The Zeal Home | Sonali Patel Design | Mumbai Interiorlover &#8211; Projects Post\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Zeal Home | Sonali Patel Design | Mumbai &#8211; Interiorlover Projects\" \/>\n<meta property=\"og:description\" content=\"The Zeal Home | Sonali Patel Design | Mumbai Interiorlover &#8211; Projects Post\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/\" \/>\n<meta property=\"og:site_name\" content=\"Interiorlover\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interiorlover.in\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-22T05:12:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-22T05:20:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1773\" \/>\n\t<meta property=\"og:image:height\" content=\"1182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Interior Lover\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Interiorlover1\" \/>\n<meta name=\"twitter:site\" content=\"@Interiorlover1\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Interior Lover\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"SocialMediaPosting\"],\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/\"},\"author\":{\"name\":\"Interior Lover\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/person\\\/32b989410f07740d451875819214d9c6\"},\"headline\":\"The Zeal Home | Sonali Patel Design | Mumbai\",\"datePublished\":\"2021-10-22T05:12:39+00:00\",\"dateModified\":\"2021-10-22T05:20:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/\"},\"wordCount\":535,\"publisher\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg\",\"keywords\":[\"apartmentinterior\",\"architecture\",\"bizouphotos\",\"interior\",\"interiordesign\",\"interiordesigninspiration\",\"interiorfurniture\",\"interiorlover.in\",\"interiorphotography\",\"interiorstyling\",\"luxury Architecture\",\"luxury interior\",\"luxuryhome\",\"modern home\",\"modern interior\",\"residentialinterior\",\"Sonali Patel Design\"],\"articleSection\":[\"Interior\",\"Projects\",\"Residential\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/\",\"name\":\"The Zeal Home | Sonali Patel Design | Mumbai &#8211; Interiorlover Projects\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg\",\"datePublished\":\"2021-10-22T05:12:39+00:00\",\"dateModified\":\"2021-10-22T05:20:52+00:00\",\"description\":\"The Zeal Home | Sonali Patel Design | Mumbai Interiorlover &#8211; Projects Post\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg\",\"contentUrl\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg\",\"width\":1773,\"height\":1182},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2021\\\/10\\\/22\\\/the-zeal-home-sonali-patel-design-mumbai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interiorlover.in\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"apartmentinterior\",\"item\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/tag\\\/apartmentinterior\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The Zeal Home | Sonali Patel Design | Mumbai\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#website\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/\",\"name\":\"Interiorlover\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interiorlover.in\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#organization\",\"name\":\"interiorlover.in\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"interiorlover.in\"},\"image\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interiorlover.in\\\/\",\"https:\\\/\\\/x.com\\\/Interiorlover1\",\"https:\\\/\\\/instagram.com\\\/interiorlover.in?igshid=1jh6qkarp6d84\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UCYgA4vx0vpdYgZbeY1djskQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/person\\\/32b989410f07740d451875819214d9c6\",\"name\":\"Interior Lover\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g\",\"caption\":\"Interior Lover\"},\"sameAs\":[\"http:\\\/\\\/interiorlover.in\"],\"url\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/author\\\/interior_lover2k20\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Zeal Home | Sonali Patel Design | Mumbai &#8211; Interiorlover Projects","description":"The Zeal Home | Sonali Patel Design | Mumbai Interiorlover &#8211; Projects Post","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/","og_locale":"en_US","og_type":"article","og_title":"The Zeal Home | Sonali Patel Design | Mumbai &#8211; Interiorlover Projects","og_description":"The Zeal Home | Sonali Patel Design | Mumbai Interiorlover &#8211; Projects Post","og_url":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/","og_site_name":"Interiorlover","article_publisher":"https:\/\/www.facebook.com\/interiorlover.in\/","article_published_time":"2021-10-22T05:12:39+00:00","article_modified_time":"2021-10-22T05:20:52+00:00","og_image":[{"width":1773,"height":1182,"url":"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg","type":"image\/jpeg"}],"author":"Interior Lover","twitter_card":"summary_large_image","twitter_creator":"@Interiorlover1","twitter_site":"@Interiorlover1","twitter_misc":{"Written by":"Interior Lover","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","SocialMediaPosting"],"@id":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/#article","isPartOf":{"@id":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/"},"author":{"name":"Interior Lover","@id":"https:\/\/interiorlover.in\/#\/schema\/person\/32b989410f07740d451875819214d9c6"},"headline":"The Zeal Home | Sonali Patel Design | Mumbai","datePublished":"2021-10-22T05:12:39+00:00","dateModified":"2021-10-22T05:20:52+00:00","mainEntityOfPage":{"@id":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/"},"wordCount":535,"publisher":{"@id":"https:\/\/interiorlover.in\/#organization"},"image":{"@id":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/#primaryimage"},"thumbnailUrl":"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg","keywords":["apartmentinterior","architecture","bizouphotos","interior","interiordesign","interiordesigninspiration","interiorfurniture","interiorlover.in","interiorphotography","interiorstyling","luxury Architecture","luxury interior","luxuryhome","modern home","modern interior","residentialinterior","Sonali Patel Design"],"articleSection":["Interior","Projects","Residential"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/","url":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/","name":"The Zeal Home | Sonali Patel Design | Mumbai &#8211; Interiorlover Projects","isPartOf":{"@id":"https:\/\/interiorlover.in\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/#primaryimage"},"image":{"@id":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/#primaryimage"},"thumbnailUrl":"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg","datePublished":"2021-10-22T05:12:39+00:00","dateModified":"2021-10-22T05:20:52+00:00","description":"The Zeal Home | Sonali Patel Design | Mumbai Interiorlover &#8211; Projects Post","breadcrumb":{"@id":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/#primaryimage","url":"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg","contentUrl":"https:\/\/interiorlover.in\/wp-content\/uploads\/2021\/10\/The-Zeal-Home-Sonali-Patel-Design-Mumbai1.jpg","width":1773,"height":1182},{"@type":"BreadcrumbList","@id":"https:\/\/interiorlover.in\/index.php\/2021\/10\/22\/the-zeal-home-sonali-patel-design-mumbai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interiorlover.in\/"},{"@type":"ListItem","position":2,"name":"apartmentinterior","item":"https:\/\/interiorlover.in\/index.php\/tag\/apartmentinterior\/"},{"@type":"ListItem","position":3,"name":"The Zeal Home | Sonali Patel Design | Mumbai"}]},{"@type":"WebSite","@id":"https:\/\/interiorlover.in\/#website","url":"https:\/\/interiorlover.in\/","name":"Interiorlover","description":"","publisher":{"@id":"https:\/\/interiorlover.in\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interiorlover.in\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/interiorlover.in\/#organization","name":"interiorlover.in","url":"https:\/\/interiorlover.in\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/interiorlover.in\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"interiorlover.in"},"image":{"@id":"https:\/\/interiorlover.in\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interiorlover.in\/","https:\/\/x.com\/Interiorlover1","https:\/\/instagram.com\/interiorlover.in?igshid=1jh6qkarp6d84","https:\/\/youtube.com\/channel\/UCYgA4vx0vpdYgZbeY1djskQ"]},{"@type":"Person","@id":"https:\/\/interiorlover.in\/#\/schema\/person\/32b989410f07740d451875819214d9c6","name":"Interior Lover","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g","caption":"Interior Lover"},"sameAs":["http:\/\/interiorlover.in"],"url":"https:\/\/interiorlover.in\/index.php\/author\/interior_lover2k20\/"}]}},"_links":{"self":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/posts\/11840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/comments?post=11840"}],"version-history":[{"count":0,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/posts\/11840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/media\/11842"}],"wp:attachment":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/media?parent=11840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/categories?post=11840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/tags?post=11840"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/powerkit_post_featured?post=11840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}