{"id":19540,"date":"2023-04-24T12:20:26","date_gmt":"2023-04-24T05:20:26","guid":{"rendered":"https:\/\/interiorlover.in\/?p=19540"},"modified":"2023-04-24T12:20:27","modified_gmt":"2023-04-24T05:20:27","slug":"mh-15-jones-arc-tales-nashik","status":"publish","type":"post","link":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/","title":{"rendered":"MH 15 Jones | ARC Tales | Nashik"},"content":{"rendered":"\n<p><strong>MH 15 Jones | <\/strong><a href=\"https:\/\/www.instagram.com\/arc.tales\/\"><strong>ARC Tales<\/strong><\/a><strong> | Nashik<\/strong><\/p>\n\n\n\n<p>It is difficult to attract clients who believe in you like this one did. They booked an apartment, set up a meeting with us, started the work and came back to India only on the day of the shoot of the house. Truly a miracle.<br><br>The brief was \u2018simple\u2019. It can\u2019t be simpler than this. The client is central to the decision to name the project MH15 Jones. The client lives in California in a building with a similar name, and the numbers \u2018MH15\u2019 represent Nashik, the project\u2019s location and also his hometown.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1000\"  height=\"666\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1-80x53.jpg\"  alt=\"\"  class=\"wp-image-19541 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1000px) 100vw, 1000px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1.jpg 1000w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1-800x533.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1-320x213.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1-560x373.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1-80x53.jpg 80w\" ><\/figure>\n\n\n\n<p>As California is known for its stunning views and relaxed lifestyle, bringing a bit of that to Nashik through an interior theme could be a great way to bring a bit of the California vibe to your home. Light and airy colours, minimalist furniture and d\u00e9cor, and a focus on plants and nature to bring the outdoors in could all be part of the interior theme. As a result, this home\u2019s interior has a modern California vibe to it.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"749\"  height=\"1000\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales2-80x107.jpg\"  alt=\"\"  class=\"wp-image-19542 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 749px) 100vw, 749px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales2.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales2.jpg 749w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales2-120x160.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales2-90x120.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales2-320x427.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales2-560x747.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales2-80x106.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales2-60x80.jpg 60w\" ><\/figure>\n\n\n\n<p>This California-themed living room features cosy colours and textures to create a welcoming and stylish atmosphere. The accent wall is coloured in an earthy orange colour to become the focal point as soon as you enter the home and break the monotony of white as seen in any other colour. Other than this the entire house is painted in a bright white shade to make the space look expansive and bright. The light grey upholstery on the sofa has clean lines and a comfortable feel. A coffee table is finished in wood and is topped with a potted succulent. On the walls, framed prints in the shade of blue and white give the room a much needed oomph. A few potted succulents scattered around the room bring a hint of nature indoors.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"750\"  height=\"1000\"  data-id=\"19543\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales3-80x107.jpg\"  alt=\"\"  class=\"wp-image-19543 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 750px) 100vw, 750px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales3.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales3.jpg 750w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales3-120x160.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales3-90x120.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales3-320x427.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales3-560x747.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales3-80x106.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales3-60x80.jpg 60w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"666\"  height=\"1000\"  data-id=\"19544\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales4-80x120.jpg\"  alt=\"\"  class=\"wp-image-19544 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 666px) 100vw, 666px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales4.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales4.jpg 666w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales4-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales4-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales4-320x480.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales4-560x841.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales4-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales4-53x80.jpg 53w\" ><\/figure>\n<\/figure>\n\n\n\n<p>Minimalistic arch designs in living room interiors provide a timeless feeling as they often feature simple, clean lines and a neutral colour palette. The combination of these characteristics results in a timeless, classic look that will never go out of style. A large area rug in a muted colour anchors the space. Furthermore, the arch design provides a sense of openness and airiness, which can help a living room feel larger and more inviting. Finally, a few decorative pillows in warm colours complete the look.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"666\"  height=\"1000\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales5-80x120.jpg\"  alt=\"\"  class=\"wp-image-19545 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 666px) 100vw, 666px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales5.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales5.jpg 666w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales5-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales5-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales5-320x480.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales5-560x841.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales5-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales5-53x80.jpg 53w\" ><\/figure>\n\n\n\n<p>The kitchen also has a modern California vibe. The cabinets are painted a beautiful shade of blue, while the backsplash is white to create a contrast. The appliances and hardware are black providing a modern and sleek look. The countertops are kept in granite, which adds a classic and elegant touch.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"666\"  height=\"1000\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales6-80x120.jpg\"  alt=\"\"  class=\"wp-image-19546 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 666px) 100vw, 666px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales6.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales6.jpg 666w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales6-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales6-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales6-320x480.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales6-560x841.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales6-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales6-53x80.jpg 53w\" ><\/figure>\n\n\n\n<p>Adjoining the kitchen is a breakfast table, which is a light wood colour with a grey top. The chairs are upholstered in a cinnamon fabric that complements the overall colour scheme of the room. The table is set with a few decorative pieces, such as a vase, creating a warm and inviting atmosphere. Breakfast tables near kitchens promote interaction because they provide an intimate setting that encourages people to converse with one another. By placing a breakfast table near the kitchen, it allows family and friends to come together in a more personal space to discuss their day.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"666\"  height=\"1000\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales7-80x120.jpg\"  alt=\"\"  class=\"wp-image-19547 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 666px) 100vw, 666px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales7.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales7.jpg 666w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales7-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales7-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales7-320x480.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales7-560x841.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales7-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales7-53x80.jpg 53w\" ><\/figure>\n\n\n\n<p>This is an ideal place to share stories, exchange ideas and strengthen bonds. Having a breakfast table near the kitchen also allows people to easily grab food and drinks while they converse. This helps to create a more relaxed atmosphere, encouraging further conversations and interaction. With its bold and cheerful atmosphere, a blue kitchen is the perfect place to cook and entertain.<\/p>\n\n\n\n<p>The bedrooms have a more traditional feel while still retaining the California vibe. The walls feature a large piece of art in a neutral colour scheme. The bedding is a mix of whites and creams, with cushioning in shades of oranges.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"666\"  height=\"1000\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales8-80x120.jpg\"  alt=\"\"  class=\"wp-image-19548 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 666px) 100vw, 666px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales8.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales8.jpg 666w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales8-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales8-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales8-320x480.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales8-560x841.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales8-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales8-53x80.jpg 53w\" ><\/figure>\n\n\n\n<p>By hiding the door near the tv unit which opens into the toilet, it helped to create a more streamlined look in the room, as well as avoided a visual breakdown of the wall. This was achieved by cleverly placing fluted strips and grooves on the wall to conceal the look. The door can be pushed to open and returns back to its position with the help of a door closer to complete the look. This helped to create a minimalistic room.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"666\"  height=\"1000\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales9-80x120.jpg\"  alt=\"\"  class=\"wp-image-19549 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 666px) 100vw, 666px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales9.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales9.jpg 666w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales9-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales9-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales9-320x480.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales9-560x841.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales9-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales9-53x80.jpg 53w\" ><\/figure>\n\n\n\n<p>In the other bedroom, colours were added to the bedding to contrast with the bed back. The blue fluted bed back is a beautiful and stylish design element that adds a touch of elegance to any bedroom. It has a timeless classic look that can be combined with other stylish accents to create a sophisticated and elegant appearance. It is a perfect way to add a touch of colour to a neutral bedroom. Because the client lives in California and visits every year, a foldable study table is a great idea because it allows him to shut it when not in use, freeing up space in your home. This type of table is ideal for people living in apartments or homes with limited space, or for those who do not have a dedicated workspace.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"666\"  height=\"1000\"  data-id=\"19550\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales10-80x120.jpg\"  alt=\"\"  class=\"wp-image-19550 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 666px) 100vw, 666px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales10.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales10.jpg 666w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales10-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales10-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales10-320x480.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales10-560x841.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales10-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales10-53x80.jpg 53w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"666\"  height=\"1000\"  data-id=\"19551\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales11-80x120.jpg\"  alt=\"\"  class=\"wp-image-19551 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 666px) 100vw, 666px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales11.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales11.jpg 666w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales11-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales11-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales11-320x480.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales11-560x841.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales11-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales11-53x80.jpg 53w\" ><\/figure>\n<\/figure>\n\n\n\n<p>This home is designed to draw inspiration from the culture and style of California, and incorporate modern architectural elements such as open floor plans, large windows, and indoor-outdoor living. It is also designed to make use of natural light and ventilation, helping to reduce energy costs. The unique design of this home makes it stand out in Nashik, providing a unique and luxurious living experience. It provides a way for Nashik residents to enjoy the best of California living without sacrificing the convenience and comfort of modern living.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"666\"  height=\"1000\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales12-80x120.jpg\"  alt=\"\"  class=\"wp-image-19552 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 666px) 100vw, 666px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales12.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales12.jpg 666w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales12-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales12-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales12-320x480.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales12-560x841.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales12-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales12-53x80.jpg 53w\" ><\/figure>\n\n\n\n<p><strong>FACT FILE<\/strong><\/p>\n\n\n\n<p><strong>Project Name : MH 15 Jones<br>Design Firm : <\/strong><a href=\"https:\/\/www.instagram.com\/arc.tales\/\"><strong>ARC Tales<\/strong><\/a><strong><br>Principal Designer : Ar. Rashi Choudhary<br>Project Location : Nashik, Maharashtra<br>Project Type : Residential Interior Design<br>Photography Credits : <\/strong><a href=\"https:\/\/www.instagram.com\/whatweclick\/\"><strong>What We Click<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MH 15 Jones | ARC Tales | Nashik It is difficult to attract clients who believe in you like this one did. They booked an apartment, set up a meeting&hellip;<\/p>\n","protected":false},"author":2,"featured_media":19541,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,35,21],"tags":[53,625,27,17,564,566,565,45,46,88,52,47,108,405,521,647,370,522,56,402,317,718,396,30,234],"powerkit_post_featured":[],"class_list":{"0":"post-19540","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-interior","8":"category-projects","9":"category-residential","10":"tag-apartmentinterior","11":"tag-arc-tales-by-rashi-choudhary","12":"tag-architecture","13":"tag-interior","14":"tag-interior-decor","15":"tag-interior-furnishings","16":"tag-interior-furniture","17":"tag-interiordesign","18":"tag-interiordesigninspiration","19":"tag-interiorfurniture","20":"tag-interiorlover-in","21":"tag-interiorphotography","22":"tag-interiorstyling","23":"tag-luxury-architecture","24":"tag-luxury-furniture","25":"tag-luxury-home","26":"tag-luxury-interior","27":"tag-luxury-lighting","28":"tag-luxuryhome","29":"tag-modern-home","30":"tag-modern-interior","31":"tag-modern-interiordesign","32":"tag-residential-interior","33":"tag-residentialinterior","34":"tag-what-we-click-photography"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MH 15 Jones | ARC Tales | Nashik &#8211; Interiorlover Projects<\/title>\n<meta name=\"description\" content=\"MH 15 Jones | ARC Tales | Nashik Interiorlover &#8211; Projects Post\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MH 15 Jones | ARC Tales | Nashik &#8211; Interiorlover Projects\" \/>\n<meta property=\"og:description\" content=\"MH 15 Jones | ARC Tales | Nashik Interiorlover &#8211; Projects Post\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/\" \/>\n<meta property=\"og:site_name\" content=\"Interiorlover\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interiorlover.in\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-24T05:20:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-24T05:20:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Interior Lover\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Interiorlover1\" \/>\n<meta name=\"twitter:site\" content=\"@Interiorlover1\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Interior Lover\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"SocialMediaPosting\"],\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/\"},\"author\":{\"name\":\"Interior Lover\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/person\\\/32b989410f07740d451875819214d9c6\"},\"headline\":\"MH 15 Jones | ARC Tales | Nashik\",\"datePublished\":\"2023-04-24T05:20:26+00:00\",\"dateModified\":\"2023-04-24T05:20:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/\"},\"wordCount\":984,\"publisher\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/MH-15-Jones-ARC-Tales1.jpg\",\"keywords\":[\"apartmentinterior\",\"ARC Tales By Rashi Choudhary\",\"architecture\",\"interior\",\"Interior Decor\",\"Interior Furnishings\",\"Interior Furniture\",\"interiordesign\",\"interiordesigninspiration\",\"interiorfurniture\",\"interiorlover.in\",\"interiorphotography\",\"interiorstyling\",\"luxury Architecture\",\"Luxury Furniture\",\"luxury Home\",\"luxury interior\",\"Luxury Lighting\",\"luxuryhome\",\"modern home\",\"modern interior\",\"modern interiordesign\",\"Residential Interior\",\"residentialinterior\",\"What We Click photography\"],\"articleSection\":[\"Interior\",\"Projects\",\"Residential\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/\",\"name\":\"MH 15 Jones | ARC Tales | Nashik &#8211; Interiorlover Projects\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/MH-15-Jones-ARC-Tales1.jpg\",\"datePublished\":\"2023-04-24T05:20:26+00:00\",\"dateModified\":\"2023-04-24T05:20:27+00:00\",\"description\":\"MH 15 Jones | ARC Tales | Nashik Interiorlover &#8211; Projects Post\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/MH-15-Jones-ARC-Tales1.jpg\",\"contentUrl\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/MH-15-Jones-ARC-Tales1.jpg\",\"width\":1000,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2023\\\/04\\\/24\\\/mh-15-jones-arc-tales-nashik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interiorlover.in\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"apartmentinterior\",\"item\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/tag\\\/apartmentinterior\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MH 15 Jones | ARC Tales | Nashik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#website\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/\",\"name\":\"Interiorlover\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interiorlover.in\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#organization\",\"name\":\"interiorlover.in\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"interiorlover.in\"},\"image\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interiorlover.in\\\/\",\"https:\\\/\\\/x.com\\\/Interiorlover1\",\"https:\\\/\\\/instagram.com\\\/interiorlover.in?igshid=1jh6qkarp6d84\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UCYgA4vx0vpdYgZbeY1djskQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/person\\\/32b989410f07740d451875819214d9c6\",\"name\":\"Interior Lover\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g\",\"caption\":\"Interior Lover\"},\"sameAs\":[\"http:\\\/\\\/interiorlover.in\"],\"url\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/author\\\/interior_lover2k20\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MH 15 Jones | ARC Tales | Nashik &#8211; Interiorlover Projects","description":"MH 15 Jones | ARC Tales | Nashik Interiorlover &#8211; Projects Post","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/","og_locale":"en_US","og_type":"article","og_title":"MH 15 Jones | ARC Tales | Nashik &#8211; Interiorlover Projects","og_description":"MH 15 Jones | ARC Tales | Nashik Interiorlover &#8211; Projects Post","og_url":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/","og_site_name":"Interiorlover","article_publisher":"https:\/\/www.facebook.com\/interiorlover.in\/","article_published_time":"2023-04-24T05:20:26+00:00","article_modified_time":"2023-04-24T05:20:27+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1.jpg","type":"image\/jpeg"}],"author":"Interior Lover","twitter_card":"summary_large_image","twitter_creator":"@Interiorlover1","twitter_site":"@Interiorlover1","twitter_misc":{"Written by":"Interior Lover"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","SocialMediaPosting"],"@id":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/#article","isPartOf":{"@id":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/"},"author":{"name":"Interior Lover","@id":"https:\/\/interiorlover.in\/#\/schema\/person\/32b989410f07740d451875819214d9c6"},"headline":"MH 15 Jones | ARC Tales | Nashik","datePublished":"2023-04-24T05:20:26+00:00","dateModified":"2023-04-24T05:20:27+00:00","mainEntityOfPage":{"@id":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/"},"wordCount":984,"publisher":{"@id":"https:\/\/interiorlover.in\/#organization"},"image":{"@id":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/#primaryimage"},"thumbnailUrl":"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1.jpg","keywords":["apartmentinterior","ARC Tales By Rashi Choudhary","architecture","interior","Interior Decor","Interior Furnishings","Interior Furniture","interiordesign","interiordesigninspiration","interiorfurniture","interiorlover.in","interiorphotography","interiorstyling","luxury Architecture","Luxury Furniture","luxury Home","luxury interior","Luxury Lighting","luxuryhome","modern home","modern interior","modern interiordesign","Residential Interior","residentialinterior","What We Click photography"],"articleSection":["Interior","Projects","Residential"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/","url":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/","name":"MH 15 Jones | ARC Tales | Nashik &#8211; Interiorlover Projects","isPartOf":{"@id":"https:\/\/interiorlover.in\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/#primaryimage"},"image":{"@id":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/#primaryimage"},"thumbnailUrl":"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1.jpg","datePublished":"2023-04-24T05:20:26+00:00","dateModified":"2023-04-24T05:20:27+00:00","description":"MH 15 Jones | ARC Tales | Nashik Interiorlover &#8211; Projects Post","breadcrumb":{"@id":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/#primaryimage","url":"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1.jpg","contentUrl":"https:\/\/interiorlover.in\/wp-content\/uploads\/2023\/04\/MH-15-Jones-ARC-Tales1.jpg","width":1000,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/interiorlover.in\/index.php\/2023\/04\/24\/mh-15-jones-arc-tales-nashik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interiorlover.in\/"},{"@type":"ListItem","position":2,"name":"apartmentinterior","item":"https:\/\/interiorlover.in\/index.php\/tag\/apartmentinterior\/"},{"@type":"ListItem","position":3,"name":"MH 15 Jones | ARC Tales | Nashik"}]},{"@type":"WebSite","@id":"https:\/\/interiorlover.in\/#website","url":"https:\/\/interiorlover.in\/","name":"Interiorlover","description":"","publisher":{"@id":"https:\/\/interiorlover.in\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interiorlover.in\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/interiorlover.in\/#organization","name":"interiorlover.in","url":"https:\/\/interiorlover.in\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/interiorlover.in\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"interiorlover.in"},"image":{"@id":"https:\/\/interiorlover.in\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interiorlover.in\/","https:\/\/x.com\/Interiorlover1","https:\/\/instagram.com\/interiorlover.in?igshid=1jh6qkarp6d84","https:\/\/youtube.com\/channel\/UCYgA4vx0vpdYgZbeY1djskQ"]},{"@type":"Person","@id":"https:\/\/interiorlover.in\/#\/schema\/person\/32b989410f07740d451875819214d9c6","name":"Interior Lover","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g","caption":"Interior Lover"},"sameAs":["http:\/\/interiorlover.in"],"url":"https:\/\/interiorlover.in\/index.php\/author\/interior_lover2k20\/"}]}},"_links":{"self":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/posts\/19540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/comments?post=19540"}],"version-history":[{"count":0,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/posts\/19540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/media\/19541"}],"wp:attachment":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/media?parent=19540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/categories?post=19540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/tags?post=19540"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/powerkit_post_featured?post=19540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}