{"id":24938,"date":"2025-01-15T00:06:00","date_gmt":"2025-01-14T17:06:00","guid":{"rendered":"https:\/\/interiorlover.in\/?p=24938"},"modified":"2025-01-14T14:02:37","modified_gmt":"2025-01-14T07:02:37","slug":"the-stone-palette-studio-arcon-pune","status":"publish","type":"post","link":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/","title":{"rendered":"The Stone Palette | Studio Arcon | Pune"},"content":{"rendered":"\n<p><strong>The Stone Palette | <\/strong><a href=\"http:\/\/www.studioarcon.in\"><strong>Studio Arcon<\/strong><\/a><strong> | Pune<\/strong><\/p>\n\n\n\n<p>Tucked away in the quiet lanes of PCMC, Pune, <strong>The Stone Palette<\/strong> by <a href=\"http:\/\/www.studioarcon.in\"><strong>Studio Arcon<\/strong><\/a> is a story of transformation. Founders and Principal Architects<strong>, Jinesh Dhumavat <\/strong>and<strong> Shekhar Nahar <\/strong>reimagine a 4.5BHK flat into a spacious 4BHK home, where the raw beauty of stone takes centre stage. Designed for a family of four, the home aligns with Vastu principles, balancing contemporary aesthetics with an earthy, welcoming warmth, all while embracing functionality at its core.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24939\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon1-80x120.jpg\"  alt=\"\"  class=\"wp-image-24939 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon1.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon1.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon1-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon1-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon1-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon1-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon1-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon1-53x80.jpg 53w\" ><\/figure>\n<\/figure>\n\n\n\n<p>At the heart of the design lies the client\u2019s bold vision: natural quartzite flooring. A conversation starter in itself, the stone energises the home with its unpolished beauty. Complementing this standout feature, the studio adopts a restrained material palette\u2014lime-plastered walls, mild steel accents, and stained veneer furniture. Splashes of playful patterns and colour breathe life into the minimalist base.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24940\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon2-80x120.jpg\"  alt=\"\"  class=\"wp-image-24940 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon2.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon2.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon2-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon2-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon2-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon2-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon2-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon2-53x80.jpg 53w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24943\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon7-80x53.jpg\"  alt=\"\"  class=\"wp-image-24943 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon7.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon7.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon7-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon7-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon7-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon7-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon7-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon7-80x53.jpg 80w\" ><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><a href=\"http:\/\/www.interiorlover.in\/\"><strong>Interior Lover team\u2019s view on the Project<\/strong><\/a><\/p>\n\n\n\n<p>Nestled in the serene surroundings of PCMC, Pune, this residence by\u00a0<strong><a href=\"http:\/\/www.studioarcon.in\/\">Studio Arcon\u00a0<\/a><\/strong>embodies a seamless blend of natural elegance and contemporary design. Spearheaded by\u00a0Architects<strong> Jinesh Dhumavat <\/strong>and<strong> Shekhar Nahar<\/strong>, the project transforms the spatial layout into a thoughtfully curated home that harmonises aesthetic sophistication with everyday functionality. Guided by Vastu principles, the design fosters an environment of balanced serenity and refined modernity.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24942\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon6-80x53.jpg\"  alt=\"\"  class=\"wp-image-24942 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon6.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon6.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon6-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon6-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon6-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon6-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon6-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon6-80x53.jpg 80w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24945\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon9-80x120.jpg\"  alt=\"\"  class=\"wp-image-24945 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon9.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon9.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon9-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon9-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon9-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon9-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon9-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon9-53x80.jpg 53w\" ><\/figure>\n<\/figure>\n\n\n\n<p>Natural stone emerges as the hero of the design narrative, anchoring the home with its raw, unpolished charm. A meticulous interplay of materials, including lime-plastered surfaces, stained veneers, and steel accents, creates a symphony of textures that exudes understated luxury. Subtle elements of colour and pattern punctuate the neutral foundation, adding layers of dynamism without overwhelming the overall restraint. This cohesive material and tonal palette evokes a timeless, earthy, contemporary, and inviting warmth.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24941\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon5-80x120.jpg\"  alt=\"\"  class=\"wp-image-24941 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon5.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon5.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon5-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon5-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon5-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon5-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon5-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon5-53x80.jpg 53w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24944\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon8-80x53.jpg\"  alt=\"\"  class=\"wp-image-24944 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon8.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon8.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon8-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon8-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon8-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon8-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon8-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon8-80x53.jpg 80w\" ><\/figure>\n<\/figure>\n\n\n\n<p>Every detail is tailored to enhance the spatial experience, balancing form and function creatively. A focus on versatility ensures that the home adapts seamlessly to its inhabitants\u2019 lifestyles, while thoughtful material explorations elevate the sensory quality of the space. <strong><a href=\"http:\/\/www.studioarcon.in\/\">Studio Arcon\u2019s<\/a><\/strong> design ethos shines through in every corner, crafting a home that is as enduring as it is inspiring.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24948\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12-80x53.jpg\"  alt=\"\"  class=\"wp-image-24948 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12-80x53.jpg 80w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24947\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon11-80x120.jpg\"  alt=\"\"  class=\"wp-image-24947 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon11.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon11.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon11-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon11-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon11-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon11-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon11-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon11-53x80.jpg 53w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24946\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon10-80x53.jpg\"  alt=\"\"  class=\"wp-image-24946 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon10.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon10.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon10-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon10-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon10-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon10-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon10-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon10-80x53.jpg 80w\" ><\/figure>\n<\/figure>\n\n\n\n<p>The living room combines slight curves with stucco-coated walls to create a chic yet earthy aesthetic. A TV partition cleverly separates the living space from the dining area, which features a custom square table and a cosy library.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24949\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon13-80x53.jpg\"  alt=\"\"  class=\"wp-image-24949 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon13.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon13.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon13-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon13-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon13-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon13-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon13-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon13-80x53.jpg 80w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24950\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon14-80x53.jpg\"  alt=\"\"  class=\"wp-image-24950 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon14.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon14.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon14-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon14-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon14-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon14-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon14-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon14-80x53.jpg 80w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24951\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon15-80x53.jpg\"  alt=\"\"  class=\"wp-image-24951 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon15.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon15.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon15-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon15-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon15-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon15-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon15-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon15-80x53.jpg 80w\" ><\/figure>\n<\/figure>\n\n\n\n<p>The quartzite becomes the muse for the home\u2019s other stone-centric features. A prime example is the water installation that separates the dining area from the modular kitchen. Crafted from Indian stones, this serene centrepiece, complete with a hidden basin, introduces the meditative sound of flowing water, creating a calming ambience. Above, a chauffeured ceiling subtly frames the dining space, marking it as the heart of the home.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24952\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon16-80x53.jpg\"  alt=\"\"  class=\"wp-image-24952 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon16.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon16.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon16-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon16-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon16-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon16-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon16-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon16-80x53.jpg 80w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24953\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon17-80x53.jpg\"  alt=\"\"  class=\"wp-image-24953 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon17.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon17.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon17-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon17-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon17-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon17-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon17-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon17-80x53.jpg 80w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24954\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon18-80x53.jpg\"  alt=\"\"  class=\"wp-image-24954 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon18.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon18.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon18-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon18-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon18-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon18-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon18-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon18-80x53.jpg 80w\" ><\/figure>\n<\/figure>\n\n\n\n<p>The parents\u2019 bedroom features a striking wooden bed back, wrapping the space in a warm, cocoon-like feel. The bed, raised on a platform, adds a playful twist, while the room flows into a walk-in wardrobe and ensuite bathroom.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24955\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon21-80x53.jpg\"  alt=\"\"  class=\"wp-image-24955 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon21.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon21.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon21-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon21-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon21-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon21-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon21-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon21-80x53.jpg 80w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24956\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon22-80x53.jpg\"  alt=\"\"  class=\"wp-image-24956 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon22.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon22.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon22-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon22-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon22-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon22-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon22-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon22-80x53.jpg 80w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24957\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon23-80x53.jpg\"  alt=\"\"  class=\"wp-image-24957 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon23.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon23.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon23-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon23-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon23-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon23-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon23-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon23-80x53.jpg 80w\" ><\/figure>\n<\/figure>\n\n\n\n<p>The younger son\u2019s room bursts with personality in bright blue and yellow. The bed back stretches all the way up to the ceiling, forming a grid filled with framed memories\u2014playful, personal, and hard to miss.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-9 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24958\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon24-80x120.jpg\"  alt=\"\"  class=\"wp-image-24958 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon24.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon24.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon24-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon24-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon24-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon24-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon24-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon24-53x80.jpg 53w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24959\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon25-80x53.jpg\"  alt=\"\"  class=\"wp-image-24959 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon25.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon25.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon25-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon25-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon25-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon25-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon25-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon25-80x53.jpg 80w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24960\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon26-80x120.jpg\"  alt=\"\"  class=\"wp-image-24960 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon26.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon26.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon26-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon26-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon26-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon26-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon26-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon26-53x80.jpg 53w\" ><\/figure>\n<\/figure>\n\n\n\n<p>In the elder son\u2019s bedroom, different shades of green come into play. The Vastu-aligned bed placement makes room for a walk-in wardrobe niche, separated by a custom sliding mirror partition that combines fun and functionality.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-10 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24961\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon27-80x53.jpg\"  alt=\"\"  class=\"wp-image-24961 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon27.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon27.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon27-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon27-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon27-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon27-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon27-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon27-80x53.jpg 80w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24962\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon28-80x53.jpg\"  alt=\"\"  class=\"wp-image-24962 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon28.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon28.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon28-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon28-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon28-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon28-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon28-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon28-80x53.jpg 80w\" ><\/figure>\n<\/figure>\n\n\n\n<p>The family\u2019s love for entertaining inspires the inclusion of a dual-purpose room. The home theatre doubles as a guest bedroom, with a spacious bed replacing traditional recliners. Windows at the rear bring in natural light and fresh air, while thick veneer walls and acoustic insulation ensure a cosy, soundproof environment perfect for movie nights.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-11 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24963\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon29-80x53.jpg\"  alt=\"\"  class=\"wp-image-24963 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon29.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon29.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon29-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon29-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon29-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon29-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon29-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon29-80x53.jpg 80w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"999\"  height=\"667\"  data-id=\"24964\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon30-80x53.jpg\"  alt=\"\"  class=\"wp-image-24964 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 999px) 100vw, 999px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon30.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon30.jpg 999w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon30-800x534.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon30-120x80.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon30-90x60.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon30-320x214.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon30-560x374.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon30-80x53.jpg 80w\" ><\/figure>\n<\/figure>\n\n\n\n<p>The tactile story extends to the bathrooms, where basalt, kota, and red granite come together in a rich mix that adds texture and depth.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-12 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24967\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon33-80x120.jpg\"  alt=\"\"  class=\"wp-image-24967 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon33.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon33.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon33-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon33-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon33-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon33-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon33-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon33-53x80.jpg 53w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24966\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon32-80x120.jpg\"  alt=\"\"  class=\"wp-image-24966 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon32.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon32.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon32-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon32-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon32-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon32-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon32-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon32-53x80.jpg 53w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24965\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon31-80x120.jpg\"  alt=\"\"  class=\"wp-image-24965 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon31.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon31.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon31-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon31-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon31-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon31-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon31-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon31-53x80.jpg 53w\" ><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-13 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24968\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon34-80x120.jpg\"  alt=\"\"  class=\"wp-image-24968 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon34.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon34.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon34-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon34-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon34-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon34-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon34-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon34-53x80.jpg 53w\" ><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"667\"  height=\"999\"  data-id=\"24969\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon35-80x120.jpg\"  alt=\"\"  class=\"wp-image-24969 pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 667px) 100vw, 667px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon35.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon35.jpg 667w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon35-120x180.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon35-90x135.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon35-320x479.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon35-560x839.jpg 560w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon35-80x120.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon35-53x80.jpg 53w\" ><\/figure>\n<\/figure>\n\n\n\n<p><strong>FACT FILE<\/strong><\/p>\n\n\n\n<p><strong>Project Name : The Stone Palette<br>Design Firm : <\/strong><a href=\"http:\/\/www.studioarcon.in\"><strong>Studio Arcon<\/strong><\/a><br><strong>Founder\/ Principal Architect : Jinesh Dhumavat and Shekhar Nahar<\/strong><br><strong>Project Location : PCMC, Pune<br>Project Year : 2024<br>Carpet Area :\u00a0 2,750 Sq Ft<br>Project Type : Residential \u2013 Interior<br>Photography Credits : <\/strong><a href=\"https:\/\/www.instagram.com\/apstudioworks\/\"><strong>Anish Padalkar<\/strong><\/a><strong><br>Text Credits : <\/strong><a href=\"https:\/\/www.instagram.com\/sneha_33\/\"><strong>Sneha Gandhi<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><a href=\"http:\/\/www.studioarcon.in\"><strong>About Studio Arcon<\/strong><\/a><\/p>\n\n\n\n<p>Established in 2010 by architects <strong>Jinesh Dhumavat<\/strong> and <strong>Shekhar Nahar<\/strong>, <a href=\"http:\/\/www.studioarcon.in\"><strong>Studio Arcon<\/strong><\/a> is an architectural practice based in PCMC\/Pune, Maharashtra. The studio specialises in residential, commercial, institutional, and mass housing projects, with a focus on blending vernacular and modern architectural styles. This approach prioritises comprehensive design solutions achieved through volume and material explorations, aiming to create spaces that evoke a sense of comfort and security.<\/p>\n\n\n\n<p>Collaboration is a cornerstone of the firm\u2019s philosophy, resulting in a diversified practice and an ever-evolving team, both within and beyond the studio. Driven by a constant urge to experiment, the creative minds at <a href=\"http:\/\/www.studioarcon.in\"><strong>Studio Arcon<\/strong><\/a> seek innovative, sustainable and socio-culturally sound solutions that are both aesthetically-pleasing and cost-effective.<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1080\"  height=\"1080\"  src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon36-80x80.jpg\"  alt=\"\"  class=\"wp-image-24970 size-full pk-lqip pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1080px) 100vw, 1080px\"  data-pk-src=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon36.jpg\"  data-pk-srcset=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon36.jpg 1080w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon36-800x800.jpg 800w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon36-80x80.jpg 80w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon36-120x120.jpg 120w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon36-90x90.jpg 90w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon36-320x320.jpg 320w, https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon36-560x560.jpg 560w\" ><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-center has-medium-font-size\"><a href=\"http:\/\/www.studioarcon.in\"><strong>Studio Arcon<\/strong><\/a><\/p>\n\n\n\n<p><strong>Website : <a href=\"http:\/\/www.studioarcon.in\">www.studioarcon.in<\/a><\/strong><\/p>\n\n\n\n<p><strong>Instagram : <a href=\"https:\/\/www.instagram.com\/studioarcon\/\">@studioarcon<\/a><\/strong><\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>The Stone Palette | Studio Arcon | Pune Tucked away in the quiet lanes of PCMC, Pune, The Stone Palette by Studio Arcon is a story of transformation. Founders and&hellip;<\/p>\n","protected":false},"author":2,"featured_media":24948,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,35,21],"tags":[53,27,722,1014,517,811,17,564,594,45,46,88,52,47,108,856,775,1024,702,991,839,30,1027],"powerkit_post_featured":[],"class_list":{"0":"post-24938","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-interior","8":"category-projects","9":"category-residential","10":"tag-apartmentinterior","11":"tag-architecture","12":"tag-classic-interior-design","13":"tag-home-design","14":"tag-homedecor","15":"tag-hotel-decor","16":"tag-interior","17":"tag-interior-decor","18":"tag-interior-design-inspiration","19":"tag-interiordesign","20":"tag-interiordesigninspiration","21":"tag-interiorfurniture","22":"tag-interiorlover-in","23":"tag-interiorphotography","24":"tag-interiorstyling","25":"tag-luxurious-exterior","26":"tag-luxurious-home","27":"tag-luxurious-interior-design","28":"tag-luxurious-interior-products","29":"tag-minimal-decor","30":"tag-modern-interior-decor","31":"tag-residentialinterior","32":"tag-studio-arcon"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Stone Palette | Studio Arcon | Pune &#8211; Interiorlover Projects<\/title>\n<meta name=\"description\" content=\"The Stone Palette | Studio Arcon | Pune Interiorlover &#8211; Projects Post\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Stone Palette | Studio Arcon | Pune &#8211; Interiorlover Projects\" \/>\n<meta property=\"og:description\" content=\"The Stone Palette | Studio Arcon | Pune Interiorlover &#8211; Projects Post\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/\" \/>\n<meta property=\"og:site_name\" content=\"Interiorlover\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interiorlover.in\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-14T17:06:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"999\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Interior Lover\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Interiorlover1\" \/>\n<meta name=\"twitter:site\" content=\"@Interiorlover1\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Interior Lover\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"SocialMediaPosting\"],\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/\"},\"author\":{\"name\":\"Interior Lover\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/person\\\/32b989410f07740d451875819214d9c6\"},\"headline\":\"The Stone Palette | Studio Arcon | Pune\",\"datePublished\":\"2025-01-14T17:06:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/\"},\"wordCount\":812,\"publisher\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/The-Stone-Palette-Studio-Arcon12.jpg\",\"keywords\":[\"apartmentinterior\",\"architecture\",\"Classic Interior Design\",\"home design\",\"HomeDecor\",\"Hotel Decor\",\"interior\",\"Interior Decor\",\"Interior Design Inspiration\",\"interiordesign\",\"interiordesigninspiration\",\"interiorfurniture\",\"interiorlover.in\",\"interiorphotography\",\"interiorstyling\",\"Luxurious Exterior\",\"Luxurious Home\",\"luxurious Interior Design\",\"Luxurious Interior Products\",\"minimal decor\",\"Modern Interior Decor\",\"residentialinterior\",\"Studio Arcon\"],\"articleSection\":[\"Interior\",\"Projects\",\"Residential\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/\",\"name\":\"The Stone Palette | Studio Arcon | Pune &#8211; Interiorlover Projects\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/The-Stone-Palette-Studio-Arcon12.jpg\",\"datePublished\":\"2025-01-14T17:06:00+00:00\",\"description\":\"The Stone Palette | Studio Arcon | Pune Interiorlover &#8211; Projects Post\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/The-Stone-Palette-Studio-Arcon12.jpg\",\"contentUrl\":\"https:\\\/\\\/interiorlover.in\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/The-Stone-Palette-Studio-Arcon12.jpg\",\"width\":999,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/2025\\\/01\\\/15\\\/the-stone-palette-studio-arcon-pune\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interiorlover.in\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"apartmentinterior\",\"item\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/tag\\\/apartmentinterior\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The Stone Palette | Studio Arcon | Pune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#website\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/\",\"name\":\"Interiorlover\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interiorlover.in\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#organization\",\"name\":\"interiorlover.in\",\"url\":\"https:\\\/\\\/interiorlover.in\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"interiorlover.in\"},\"image\":{\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interiorlover.in\\\/\",\"https:\\\/\\\/x.com\\\/Interiorlover1\",\"https:\\\/\\\/instagram.com\\\/interiorlover.in?igshid=1jh6qkarp6d84\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UCYgA4vx0vpdYgZbeY1djskQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interiorlover.in\\\/#\\\/schema\\\/person\\\/32b989410f07740d451875819214d9c6\",\"name\":\"Interior Lover\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g\",\"caption\":\"Interior Lover\"},\"sameAs\":[\"http:\\\/\\\/interiorlover.in\"],\"url\":\"https:\\\/\\\/interiorlover.in\\\/index.php\\\/author\\\/interior_lover2k20\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Stone Palette | Studio Arcon | Pune &#8211; Interiorlover Projects","description":"The Stone Palette | Studio Arcon | Pune Interiorlover &#8211; Projects Post","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/","og_locale":"en_US","og_type":"article","og_title":"The Stone Palette | Studio Arcon | Pune &#8211; Interiorlover Projects","og_description":"The Stone Palette | Studio Arcon | Pune Interiorlover &#8211; Projects Post","og_url":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/","og_site_name":"Interiorlover","article_publisher":"https:\/\/www.facebook.com\/interiorlover.in\/","article_published_time":"2025-01-14T17:06:00+00:00","og_image":[{"width":999,"height":667,"url":"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12.jpg","type":"image\/jpeg"}],"author":"Interior Lover","twitter_card":"summary_large_image","twitter_creator":"@Interiorlover1","twitter_site":"@Interiorlover1","twitter_misc":{"Written by":"Interior Lover","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","SocialMediaPosting"],"@id":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/#article","isPartOf":{"@id":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/"},"author":{"name":"Interior Lover","@id":"https:\/\/interiorlover.in\/#\/schema\/person\/32b989410f07740d451875819214d9c6"},"headline":"The Stone Palette | Studio Arcon | Pune","datePublished":"2025-01-14T17:06:00+00:00","mainEntityOfPage":{"@id":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/"},"wordCount":812,"publisher":{"@id":"https:\/\/interiorlover.in\/#organization"},"image":{"@id":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/#primaryimage"},"thumbnailUrl":"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12.jpg","keywords":["apartmentinterior","architecture","Classic Interior Design","home design","HomeDecor","Hotel Decor","interior","Interior Decor","Interior Design Inspiration","interiordesign","interiordesigninspiration","interiorfurniture","interiorlover.in","interiorphotography","interiorstyling","Luxurious Exterior","Luxurious Home","luxurious Interior Design","Luxurious Interior Products","minimal decor","Modern Interior Decor","residentialinterior","Studio Arcon"],"articleSection":["Interior","Projects","Residential"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/","url":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/","name":"The Stone Palette | Studio Arcon | Pune &#8211; Interiorlover Projects","isPartOf":{"@id":"https:\/\/interiorlover.in\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/#primaryimage"},"image":{"@id":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/#primaryimage"},"thumbnailUrl":"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12.jpg","datePublished":"2025-01-14T17:06:00+00:00","description":"The Stone Palette | Studio Arcon | Pune Interiorlover &#8211; Projects Post","breadcrumb":{"@id":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/#primaryimage","url":"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12.jpg","contentUrl":"https:\/\/interiorlover.in\/wp-content\/uploads\/2025\/01\/The-Stone-Palette-Studio-Arcon12.jpg","width":999,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/interiorlover.in\/index.php\/2025\/01\/15\/the-stone-palette-studio-arcon-pune\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interiorlover.in\/"},{"@type":"ListItem","position":2,"name":"apartmentinterior","item":"https:\/\/interiorlover.in\/index.php\/tag\/apartmentinterior\/"},{"@type":"ListItem","position":3,"name":"The Stone Palette | Studio Arcon | Pune"}]},{"@type":"WebSite","@id":"https:\/\/interiorlover.in\/#website","url":"https:\/\/interiorlover.in\/","name":"Interiorlover","description":"","publisher":{"@id":"https:\/\/interiorlover.in\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interiorlover.in\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/interiorlover.in\/#organization","name":"interiorlover.in","url":"https:\/\/interiorlover.in\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/interiorlover.in\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"interiorlover.in"},"image":{"@id":"https:\/\/interiorlover.in\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interiorlover.in\/","https:\/\/x.com\/Interiorlover1","https:\/\/instagram.com\/interiorlover.in?igshid=1jh6qkarp6d84","https:\/\/youtube.com\/channel\/UCYgA4vx0vpdYgZbeY1djskQ"]},{"@type":"Person","@id":"https:\/\/interiorlover.in\/#\/schema\/person\/32b989410f07740d451875819214d9c6","name":"Interior Lover","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08b8c1a4d79682e32ba4b52ff90dc11d255c0ac5eb9e67e8086a7abdcc4d1a7e?s=96&d=mm&r=g","caption":"Interior Lover"},"sameAs":["http:\/\/interiorlover.in"],"url":"https:\/\/interiorlover.in\/index.php\/author\/interior_lover2k20\/"}]}},"_links":{"self":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/posts\/24938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/comments?post=24938"}],"version-history":[{"count":4,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/posts\/24938\/revisions"}],"predecessor-version":[{"id":24993,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/posts\/24938\/revisions\/24993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/media\/24948"}],"wp:attachment":[{"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/media?parent=24938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/categories?post=24938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/tags?post=24938"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/interiorlover.in\/index.php\/wp-json\/wp\/v2\/powerkit_post_featured?post=24938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}